{"id":1076,"count":1,"description":"","link":"https:\/\/nofloods.com\/de\/category\/artikel\/randbemerkungen\/","name":"Randbemerkungen","slug":"randbemerkungen","taxonomy":"category","parent":1075,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Randbemerkungen Archives - NoFloods<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/nofloods.com\/de\/category\/artikel\/randbemerkungen\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Randbemerkungen Archives - NoFloods\" \/>\n<meta property=\"og:url\" content=\"https:\/\/nofloods.com\/de\/category\/artikel\/randbemerkungen\/\" \/>\n<meta property=\"og:site_name\" content=\"NoFloods\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@NoFloodsBarrier\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/nofloods.com\\\/de\\\/category\\\/artikel\\\/randbemerkungen\\\/\",\"url\":\"https:\\\/\\\/nofloods.com\\\/de\\\/category\\\/artikel\\\/randbemerkungen\\\/\",\"name\":\"Randbemerkungen Archives - NoFloods\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/nofloods.com\\\/de\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/nofloods.com\\\/de\\\/category\\\/artikel\\\/randbemerkungen\\\/#breadcrumb\"},\"inLanguage\":\"de\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/nofloods.com\\\/de\\\/category\\\/artikel\\\/randbemerkungen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/nofloods.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Artikel\",\"item\":\"https:\\\/\\\/nofloods.com\\\/de\\\/category\\\/artikel\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Randbemerkungen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/nofloods.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/nofloods.com\\\/de\\\/\",\"name\":\"NoFloods\",\"description\":\"By Environment Solutions\",\"publisher\":{\"@id\":\"https:\\\/\\\/nofloods.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/nofloods.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/nofloods.com\\\/de\\\/#organization\",\"name\":\"NoFloods\",\"url\":\"https:\\\/\\\/nofloods.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/nofloods.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/nofloods.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/NoFloods-EasyWall-Logo.webp?wsr\",\"contentUrl\":\"https:\\\/\\\/nofloods.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/NoFloods-EasyWall-Logo.webp?wsr\",\"width\":340,\"height\":70,\"caption\":\"NoFloods\"},\"image\":{\"@id\":\"https:\\\/\\\/nofloods.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/environmentsolutions\\\/\",\"https:\\\/\\\/x.com\\\/NoFloodsBarrier\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/environment-solutions-aps\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Randbemerkungen Archives - NoFloods","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/nofloods.com\/de\/category\/artikel\/randbemerkungen\/","og_locale":"de_DE","og_type":"article","og_title":"Randbemerkungen Archives - NoFloods","og_url":"https:\/\/nofloods.com\/de\/category\/artikel\/randbemerkungen\/","og_site_name":"NoFloods","twitter_card":"summary_large_image","twitter_site":"@NoFloodsBarrier","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/nofloods.com\/de\/category\/artikel\/randbemerkungen\/","url":"https:\/\/nofloods.com\/de\/category\/artikel\/randbemerkungen\/","name":"Randbemerkungen Archives - NoFloods","isPartOf":{"@id":"https:\/\/nofloods.com\/de\/#website"},"breadcrumb":{"@id":"https:\/\/nofloods.com\/de\/category\/artikel\/randbemerkungen\/#breadcrumb"},"inLanguage":"de"},{"@type":"BreadcrumbList","@id":"https:\/\/nofloods.com\/de\/category\/artikel\/randbemerkungen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/nofloods.com\/de\/"},{"@type":"ListItem","position":2,"name":"Artikel","item":"https:\/\/nofloods.com\/de\/category\/artikel\/"},{"@type":"ListItem","position":3,"name":"Randbemerkungen"}]},{"@type":"WebSite","@id":"https:\/\/nofloods.com\/de\/#website","url":"https:\/\/nofloods.com\/de\/","name":"NoFloods","description":"By Environment Solutions","publisher":{"@id":"https:\/\/nofloods.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/nofloods.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/nofloods.com\/de\/#organization","name":"NoFloods","url":"https:\/\/nofloods.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/nofloods.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/nofloods.com\/wp-content\/uploads\/2025\/05\/NoFloods-EasyWall-Logo.webp?wsr","contentUrl":"https:\/\/nofloods.com\/wp-content\/uploads\/2025\/05\/NoFloods-EasyWall-Logo.webp?wsr","width":340,"height":70,"caption":"NoFloods"},"image":{"@id":"https:\/\/nofloods.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/environmentsolutions\/","https:\/\/x.com\/NoFloodsBarrier","https:\/\/www.linkedin.com\/company\/environment-solutions-aps"]}]}},"_links":{"self":[{"href":"https:\/\/nofloods.com\/de\/wp-json\/wp\/v2\/categories\/1076","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nofloods.com\/de\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/nofloods.com\/de\/wp-json\/wp\/v2\/taxonomies\/category"}],"up":[{"embeddable":true,"href":"https:\/\/nofloods.com\/de\/wp-json\/wp\/v2\/categories\/1075"}],"wp:post_type":[{"href":"https:\/\/nofloods.com\/de\/wp-json\/wp\/v2\/posts?categories=1076"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}