{"id":13989,"date":"2025-06-25T11:25:41","date_gmt":"2025-06-25T11:25:41","guid":{"rendered":"https:\/\/flood-protection.org\/temporaere-bypass-barriere\/"},"modified":"2025-09-18T11:08:36","modified_gmt":"2025-09-18T11:08:36","slug":"bypass","status":"publish","type":"page","link":"https:\/\/nofloods.com\/de\/bypass\/","title":{"rendered":"Bypass"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"13989\" class=\"elementor elementor-13989 elementor-5538\">\n\t\t\t\t<div class=\"elementor-element elementor-element-78997106 e-flex e-con-boxed e-con e-parent\" data-id=\"78997106\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-1afa5799 e-con-full e-flex e-con e-child\" data-id=\"1afa5799\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3c28dada elementor-widget elementor-widget-heading\" data-id=\"3c28dada\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Tempor\u00e4re Bypass Wasserbarriere<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-308f11c7 elementor-widget elementor-widget-eael-breadcrumbs\" data-id=\"308f11c7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"eael-breadcrumbs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"eael-breadcrumbs\">\n\t\t\t<div class=\"eael-breadcrumbs__content\"><a href=\"https:\/\/nofloods.com\/de\/\">Home<\/a> <span class=\"eael-breadcrumb-separator\">&gt;<\/span> <span class = \"eael-current\">Seite<\/span><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1c2d7cb e-flex e-con-boxed e-con e-parent\" data-id=\"1c2d7cb\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-a88364f e-flex e-con-boxed e-con e-child\" data-id=\"a88364f\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1850110 elementor-widget elementor-widget-heading\" data-id=\"1850110\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Nachhaltiger Bypass f\u00fcr Fluss- und Bacharbeiten.<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0de480b elementor-widget elementor-widget-text-editor\" data-id=\"0de480b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tDie Durchf\u00fchrung von Bauarbeiten im \u201eWasser\u201c ist schwierig, und die Einrichtung trockener Arbeitsbereiche ist oft kostspielig, zeitaufwendig und natursch\u00e4digend.\n<br>Der traditionelle Ansatz bestand darin, D\u00e4mme oberhalb zu bauen und mit gro\u00dfen Pumpen Wasser flussabw\u00e4rts zu transportieren.\n<br>Selbst kleinere B\u00e4che erfordern einen gro\u00dfen Pumpenaufbau, und dies kann zu radikalen Eingriffen in Natur und Tierwelt f\u00fchren.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3ebec88b e-flex e-con-boxed e-con e-parent\" data-id=\"3ebec88b\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-ea99463 e-con-full e-flex e-con e-child\" data-id=\"ea99463\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-479ffa9 e-con-full e-flex e-con e-child\" data-id=\"479ffa9\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4e64ede e-con-full e-flex e-con e-child\" data-id=\"4e64ede\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-29220ce elementor-widget elementor-widget-heading\" data-id=\"29220ce\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">\u201eBypass-Barrieren\u201c \u2013 Eine nachhaltigere L\u00f6sung<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b497013 elementor-widget elementor-widget-text-editor\" data-id=\"b497013\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Wir haben unsere erfolgreiche Erfahrung aus der Hochwasserindustrie angewendet, um ein \u201eBypass System\u201c zu schaffen, das auf einfache Weise einen trockenen Arbeitsbereich innerhalb eines Gew\u00e4ssers schafft.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4e9c8a6 e-con-full e-flex e-con e-child\" data-id=\"4e9c8a6\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-05f6517 e-con-full e-flex e-con e-child\" data-id=\"05f6517\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;video&quot;,&quot;background_video_link&quot;:&quot;https:\\\/\\\/www.youtube.com\\\/watch?v=3ORzxVcQCB4&quot;,&quot;background_play_on_mobile&quot;:&quot;yes&quot;}\">\n\t\t<div class=\"elementor-background-video-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-video-embed\" role=\"presentation\"><\/div>\n\t\t\t\t\t\t<\/div>\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-bc17b3e e-con-full e-flex e-con e-child\" data-id=\"bc17b3e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3b1395c elementor-widget elementor-widget-heading\" data-id=\"3b1395c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">So funktioniert es<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-18a0547 elementor-widget elementor-widget-text-editor\" data-id=\"18a0547\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Wir verwenden unsere selbstaufrichtende Barriere (NoFloods FlexWall), um das Wasser stromaufw\u00e4rts aufzustauen und es mithilfe der Schwerkraft in unseren wassergef\u00fcllt NoFloods Barrieren stromabw\u00e4rts zu transportieren.<\/p><p>Es werden keine Pumpen, energieverbrauchenden Maschinen oder Methoden verwendet, die die Umwelt auf andere Weise beeintr\u00e4chtigen w\u00fcrden.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6f8cd5a e-con-full e-flex e-con e-child\" data-id=\"6f8cd5a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-27711ec e-con-full e-flex e-con e-child\" data-id=\"27711ec\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;video&quot;,&quot;background_video_link&quot;:&quot;https:\\\/\\\/www.youtube.com\\\/watch?v=8bghbjzGKuo&quot;,&quot;background_play_on_mobile&quot;:&quot;yes&quot;}\">\n\t\t<div class=\"elementor-background-video-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-video-embed\" role=\"presentation\"><\/div>\n\t\t\t\t\t\t<\/div>\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-2c129cc e-con-full e-flex e-con e-child\" data-id=\"2c129cc\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-554c30b elementor-widget elementor-widget-heading\" data-id=\"554c30b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Dieses neue \u201eBypass-System\u201c ist wirtschaftlich &amp; \u00f6kologisch nachhaltig<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8a63e1e elementor-widget elementor-widget-text-editor\" data-id=\"8a63e1e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>1. Es ist wirtschaftlich, da es nur sehr wenig Personal ben\u00f6tigt, um es schnell einzusetzen, und es verbraucht keine Energie. Dies gew\u00e4hrleistet eine starke Kosten-Nutzen-Rechnung. <\/p><p>2. Es ist \u00f6kologisch nachhaltig, da es manuell oder mit begrenzter mechanischer Hilfe eingesetzt und entfernt wird. Dar\u00fcber hinaus k\u00f6nnen Wildtiere wie Fische, Sedimente und Mikroorganismen w\u00e4hrend der Arbeiten leicht und schonend durch die Schl\u00e4uche gelangen. <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b4db61d e-flex e-con-boxed e-con e-parent\" data-id=\"b4db61d\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-88e45cd e-flex e-con-boxed e-con e-child\" data-id=\"88e45cd\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b3f6fd6 elementor-widget elementor-widget-heading\" data-id=\"b3f6fd6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Weitere Vorteile der Verwendung des NoFloods Bypass-Systems<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-c532336 e-con-full e-flex e-con e-child\" data-id=\"c532336\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-3d12d83 e-con-full e-flex e-con e-child\" data-id=\"3d12d83\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-104019d elementor-view-default elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"104019d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-clock\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256,8C119,8,8,119,8,256S119,504,256,504,504,393,504,256,393,8,256,8Zm92.49,313h0l-20,25a16,16,0,0,1-22.49,2.5h0l-67-49.72a40,40,0,0,1-15-31.23V112a16,16,0,0,1,16-16h32a16,16,0,0,1,16,16V256l58,42.5A16,16,0,0,1,348.49,321Z\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h6 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tEs spart Zeit\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h6>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tEs dauert nur wenige Stunden, bis geschultes Personal das NoFloods Bypass-System einsatzbereit macht. \n\nDies bedeutet, dass ein Projekt innerhalb kurzer Zeit gestartet werden kann. Es dauert auch nur wenige Stunden, bis dasselbe geschulte Personal es nach Abschluss eines Projekts entfernt. \t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3d4c89e e-con-full e-flex e-con e-child\" data-id=\"3d4c89e\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ffdb0cf elementor-view-default elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"ffdb0cf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-deaf\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M216 260c0 15.464-12.536 28-28 28s-28-12.536-28-28c0-44.112 35.888-80 80-80s80 35.888 80 80c0 15.464-12.536 28-28 28s-28-12.536-28-28c0-13.234-10.767-24-24-24s-24 10.766-24 24zm24-176c-97.047 0-176 78.953-176 176 0 15.464 12.536 28 28 28s28-12.536 28-28c0-66.168 53.832-120 120-120s120 53.832 120 120c0 75.164-71.009 70.311-71.997 143.622L288 404c0 28.673-23.327 52-52 52-15.464 0-28 12.536-28 28s12.536 28 28 28c59.475 0 107.876-48.328 108-107.774.595-34.428 72-48.24 72-144.226 0-97.047-78.953-176-176-176zm268.485-52.201L480.2 3.515c-4.687-4.686-12.284-4.686-16.971 0L376.2 90.544c-4.686 4.686-4.686 12.284 0 16.971l28.285 28.285c4.686 4.686 12.284 4.686 16.97 0l87.03-87.029c4.687-4.688 4.687-12.286 0-16.972zM168.97 314.745c-4.686-4.686-12.284-4.686-16.97 0L3.515 463.23c-4.686 4.686-4.686 12.284 0 16.971L31.8 508.485c4.687 4.686 12.284 4.686 16.971 0L197.256 360c4.686-4.686 4.686-12.284 0-16.971l-28.286-28.284z\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h6 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tEs gibt keine L\u00e4rmbel\u00e4stigung\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h6>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tDem System ist kein elektrischer oder mechanischer L\u00e4rm zuzuschreiben, da es keine Energie verbraucht. Dies ist ein gro\u00dfer Vorteil, insbesondere wenn Bauarbeiten in der N\u00e4he eines Wohngebiets durchgef\u00fchrt werden m\u00fcssen. \t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-31308ab e-con-full e-flex e-con e-child\" data-id=\"31308ab\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4761226 elementor-view-default elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"4761226\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-boxes\" viewBox=\"0 0 576 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M560 288h-80v96l-32-21.3-32 21.3v-96h-80c-8.8 0-16 7.2-16 16v192c0 8.8 7.2 16 16 16h224c8.8 0 16-7.2 16-16V304c0-8.8-7.2-16-16-16zm-384-64h224c8.8 0 16-7.2 16-16V16c0-8.8-7.2-16-16-16h-80v96l-32-21.3L256 96V0h-80c-8.8 0-16 7.2-16 16v192c0 8.8 7.2 16 16 16zm64 64h-80v96l-32-21.3L96 384v-96H16c-8.8 0-16 7.2-16 16v192c0 8.8 7.2 16 16 16h224c8.8 0 16-7.2 16-16V304c0-8.8-7.2-16-16-16z\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h6 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tEinfach zu lagern\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h6>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tDas NoFloods Bypass System kann problemlos in einer gro\u00dfen Kiste gelagert werden. Es ben\u00f6tigt keinen gro\u00dfen Lagerraum wie andere L\u00f6sungen. \t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-2c9cef3f e-flex e-con-boxed e-con e-parent\" data-id=\"2c9cef3f\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-65a78fd9 e-con-full e-flex e-con e-child\" data-id=\"65a78fd9\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-17462f6 elementor-widget elementor-widget-heading\" data-id=\"17462f6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Beispiele f\u00fcr das Bypass-System in Aktion<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-350a7384 tpg-wrapper-align-center readmore-btn-only-text meta-visibility-show title_position_default title_hover_border_default title-default img_hover_animation_default meta_position_default grid-hover-overlay-type-always tpg-el-box-border-enable tpg-border-bottom-disable elementor-widget elementor-widget-tpg-grid-layout\" data-id=\"350a7384\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"tpg-grid-layout.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"rt-container-fluid rt-tpg-container tpg-el-main-wrapper clearfix grid-layout1-main \"\n\t\t\t id=\"rt-tpg-container-1778863205\"\n\t\t\t data-layout=\"grid-layout1\"\n\t\t\t data-grid-style=\"tpg-full-height\"\n\t\t\t data-sc-id=\"elementor\"\n\t\t\t data-el-settings=''\n\t\t\t data-el-query=''\n\t\t\t data-el-path=''\n\t\t>\n\t\t\t\t\t\t<div class='tpg-header-wrapper '>\n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t<div data-title=\"Loading ...\" class=\"rt-row rt-content-loader grid-layout1 grid-behaviour tpg-full-height grid_layout_wrapper\">\n\t\t\t\t<div class=\"rt-col-md-12 rt-col-sm-6 rt-col-xs-12 default rt-grid-item post-17244 post type-post status-publish format-standard has-post-thumbnail hentry category-fallstudien tag-bypass-stadtischer-flusse tag-bypass-temporare-barriere tag-bypass-temporare-rohre tag-bypass-von-wasserlaufen-und-kanalen tag-bypass-von-wasserwegen tag-bypass-kanale tag-umleitung-von-bachen\"        data-id=\"17244\">\n    <div class=\"rt-holder tpg-post-holder \">\n        <div class=\"rt-detail rt-el-content-wrapper\">\n\t\t\t                <div class=\"rt-img-holder tpg-el-image-wrap has-thumbnail\">\n\t\t\t\t\t<a data-id=\"17244\" href=\"https:\/\/nofloods.com\/de\/wasser-bypass-von-baechen-und-kanaelen-der-wirtschaftlich-und-oekologisch-nachhaltige-ansatz\/\" class=\"tpg-post-link\" target=\"_self\">                        <img fetchpriority=\"high\" decoding=\"async\" src=\"https:\/\/nofloods.com\/wp-content\/uploads\/2021\/10\/Water-Bypass-of-Streams-Canals-1140x445-1.jpg?wsr\"\n                             class=\"rt-img-responsive\"\n                             width=\"1140\"\n                             height=\"445\"\n                             alt=\"Wasser-Bypass von B\u00e4chen  Kan\u00e4len: der wirtschaftlich und \u00f6kologisch nachhaltige Ansatz\">\n                        \n                            \n        <\/a>\n                <div class=\"overlay grid-hover-content\"><\/div>\n                        <\/div>\n\t\t\t\n\t\t\t<div class=\"entry-title-wrapper\"><h3 class=\"entry-title\"><a data-id=\"17244\" href=\"https:\/\/nofloods.com\/de\/wasser-bypass-von-baechen-und-kanaelen-der-wirtschaftlich-und-oekologisch-nachhaltige-ansatz\/\" class=\"tpg-post-link\" target=\"_self\">Wasser-Bypass von B\u00e4chen  Kan\u00e4len: der wirtschaftlich und \u00f6kologisch nachhaltige Ansatz<\/a><\/h3><\/div>\n\t\t\t                <div class=\"post-meta-tags rt-el-post-meta\">\n\t\t\t\t\t            <span class='date'>\n\t\t\t\t<i class='far fa-calendar-alt '><\/i>                                    <a href=\"https:\/\/nofloods.com\/de\/2021\/10\/28\/\">\n\t\t\t\t\t28. Oktober 2021\t\t\t\t<\/a>\n                \t\t\t<\/span>\n                            <\/div>\n\t\t\t\n\n\t\t\t                <div class=\"tpg-excerpt tpg-el-excerpt\">\n\t\t\t\t\t                        <div class=\"tpg-excerpt-inner\">\n\t\t\t\t\t\t\tDie \u201eMetsterM\u00fchle\u201c in Sint-Truiden, Belgien, sollte von Auftragnehmer ABB im Auftrag des Eigent\u00fcmers einer gr\u00fcndlichen architektonischen Renovierung unterzogen werden. Die...                        <\/div>\n\t\t\t\t\t\t\t\t\t\t                <\/div>\n\t\t\t\n\t\t\t        <div class=\"post-footer\">\n            <div class=\"post-footer\">\n                <div class=\"read-more\">\n                    <a data-id=\"17244\" href=\"https:\/\/nofloods.com\/de\/wasser-bypass-von-baechen-und-kanaelen-der-wirtschaftlich-und-oekologisch-nachhaltige-ansatz\/\" class=\"tpg-post-link\" target=\"_self\">Read More<\/a>                <\/div>\n            <\/div>\n        <\/div>\n                <\/div>\n    <\/div>\n<\/div>\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Tempor\u00e4re Bypass Wasserbarriere Home &gt; Nachhaltiger Bypass f\u00fcr Fluss- und Bacharbeiten. Die Durchf\u00fchrung von Bauarbeiten im \u201eWasser\u201c ist schwierig, und [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"_acf_changed":false,"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"class_list":["post-13989","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Hochwasserschutz: Bypass-Systeme | NoFloods Konstruktion<\/title>\n<meta name=\"description\" content=\"Kundenspezifische Bypass L\u00f6sungen, die entwickelt wurden, um den Wasserfluss umzuleiten und Bauzonen vor \u00dcberschwemmungen zu sch\u00fctzen.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/nofloods.com\/de\/bypass\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Hochwasserschutz: Bypass-Systeme | NoFloods Konstruktion\" \/>\n<meta property=\"og:description\" content=\"Kundenspezifische Bypass L\u00f6sungen, die entwickelt wurden, um den Wasserfluss umzuleiten und Bauzonen vor \u00dcberschwemmungen zu sch\u00fctzen.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/nofloods.com\/de\/bypass\/\" \/>\n<meta property=\"og:site_name\" content=\"NoFloods\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/environmentsolutions\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-18T11:08:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/nofloods.com\/wp-content\/uploads\/2021\/10\/Water-Bypass-of-Streams-Canals-1140x445-1.jpg?wsr\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@NoFloodsBarrier\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/nofloods.com\\\/de\\\/bypass\\\/\",\"url\":\"https:\\\/\\\/nofloods.com\\\/de\\\/bypass\\\/\",\"name\":\"Hochwasserschutz: Bypass-Systeme | NoFloods Konstruktion\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/nofloods.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/nofloods.com\\\/de\\\/bypass\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/nofloods.com\\\/de\\\/bypass\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/nofloods.com\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/Water-Bypass-of-Streams-Canals-1140x445-1.jpg?wsr\",\"datePublished\":\"2025-06-25T11:25:41+00:00\",\"dateModified\":\"2025-09-18T11:08:36+00:00\",\"description\":\"Kundenspezifische Bypass L\u00f6sungen, die entwickelt wurden, um den Wasserfluss umzuleiten und Bauzonen vor \u00dcberschwemmungen zu sch\u00fctzen.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/nofloods.com\\\/de\\\/bypass\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/nofloods.com\\\/de\\\/bypass\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/nofloods.com\\\/de\\\/bypass\\\/#primaryimage\",\"url\":\"https:\\\/\\\/nofloods.com\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/Water-Bypass-of-Streams-Canals-1140x445-1.jpg?wsr\",\"contentUrl\":\"https:\\\/\\\/nofloods.com\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/Water-Bypass-of-Streams-Canals-1140x445-1.jpg?wsr\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/nofloods.com\\\/de\\\/bypass\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/nofloods.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Bypass\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/nofloods.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/nofloods.com\\\/de\\\/\",\"name\":\"NoFloods\",\"description\":\"By Environment Solutions\",\"publisher\":{\"@id\":\"https:\\\/\\\/nofloods.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/nofloods.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/nofloods.com\\\/de\\\/#organization\",\"name\":\"NoFloods\",\"url\":\"https:\\\/\\\/nofloods.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/nofloods.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/nofloods.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/NoFloods-EasyWall-Logo.webp?wsr\",\"contentUrl\":\"https:\\\/\\\/nofloods.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/NoFloods-EasyWall-Logo.webp?wsr\",\"width\":340,\"height\":70,\"caption\":\"NoFloods\"},\"image\":{\"@id\":\"https:\\\/\\\/nofloods.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/environmentsolutions\\\/\",\"https:\\\/\\\/x.com\\\/NoFloodsBarrier\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/environment-solutions-aps\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Hochwasserschutz: Bypass-Systeme | NoFloods Konstruktion","description":"Kundenspezifische Bypass L\u00f6sungen, die entwickelt wurden, um den Wasserfluss umzuleiten und Bauzonen vor \u00dcberschwemmungen zu sch\u00fctzen.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/nofloods.com\/de\/bypass\/","og_locale":"de_DE","og_type":"article","og_title":"Hochwasserschutz: Bypass-Systeme | NoFloods Konstruktion","og_description":"Kundenspezifische Bypass L\u00f6sungen, die entwickelt wurden, um den Wasserfluss umzuleiten und Bauzonen vor \u00dcberschwemmungen zu sch\u00fctzen.","og_url":"https:\/\/nofloods.com\/de\/bypass\/","og_site_name":"NoFloods","article_publisher":"https:\/\/www.facebook.com\/environmentsolutions\/","article_modified_time":"2025-09-18T11:08:36+00:00","og_image":[{"url":"https:\/\/nofloods.com\/wp-content\/uploads\/2021\/10\/Water-Bypass-of-Streams-Canals-1140x445-1.jpg?wsr","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_site":"@NoFloodsBarrier","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/nofloods.com\/de\/bypass\/","url":"https:\/\/nofloods.com\/de\/bypass\/","name":"Hochwasserschutz: Bypass-Systeme | NoFloods Konstruktion","isPartOf":{"@id":"https:\/\/nofloods.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/nofloods.com\/de\/bypass\/#primaryimage"},"image":{"@id":"https:\/\/nofloods.com\/de\/bypass\/#primaryimage"},"thumbnailUrl":"https:\/\/nofloods.com\/wp-content\/uploads\/2021\/10\/Water-Bypass-of-Streams-Canals-1140x445-1.jpg?wsr","datePublished":"2025-06-25T11:25:41+00:00","dateModified":"2025-09-18T11:08:36+00:00","description":"Kundenspezifische Bypass L\u00f6sungen, die entwickelt wurden, um den Wasserfluss umzuleiten und Bauzonen vor \u00dcberschwemmungen zu sch\u00fctzen.","breadcrumb":{"@id":"https:\/\/nofloods.com\/de\/bypass\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/nofloods.com\/de\/bypass\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/nofloods.com\/de\/bypass\/#primaryimage","url":"https:\/\/nofloods.com\/wp-content\/uploads\/2021\/10\/Water-Bypass-of-Streams-Canals-1140x445-1.jpg?wsr","contentUrl":"https:\/\/nofloods.com\/wp-content\/uploads\/2021\/10\/Water-Bypass-of-Streams-Canals-1140x445-1.jpg?wsr"},{"@type":"BreadcrumbList","@id":"https:\/\/nofloods.com\/de\/bypass\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/nofloods.com\/de\/"},{"@type":"ListItem","position":2,"name":"Bypass"}]},{"@type":"WebSite","@id":"https:\/\/nofloods.com\/de\/#website","url":"https:\/\/nofloods.com\/de\/","name":"NoFloods","description":"By Environment Solutions","publisher":{"@id":"https:\/\/nofloods.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/nofloods.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/nofloods.com\/de\/#organization","name":"NoFloods","url":"https:\/\/nofloods.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/nofloods.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/nofloods.com\/wp-content\/uploads\/2025\/05\/NoFloods-EasyWall-Logo.webp?wsr","contentUrl":"https:\/\/nofloods.com\/wp-content\/uploads\/2025\/05\/NoFloods-EasyWall-Logo.webp?wsr","width":340,"height":70,"caption":"NoFloods"},"image":{"@id":"https:\/\/nofloods.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/environmentsolutions\/","https:\/\/x.com\/NoFloodsBarrier","https:\/\/www.linkedin.com\/company\/environment-solutions-aps"]}]}},"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"nofloods_admin","author_link":"https:\/\/nofloods.com\/de\/author\/nofloods_admin\/"},"rttpg_comment":0,"rttpg_category":"","rttpg_excerpt":"Tempor\u00e4re Bypass Wasserbarriere Home &gt; Nachhaltiger Bypass f\u00fcr Fluss- und Bacharbeiten. Die Durchf\u00fchrung von Bauarbeiten im \u201eWasser\u201c ist schwierig, und [&hellip;]","_links":{"self":[{"href":"https:\/\/nofloods.com\/de\/wp-json\/wp\/v2\/pages\/13989","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nofloods.com\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/nofloods.com\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/nofloods.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/nofloods.com\/de\/wp-json\/wp\/v2\/comments?post=13989"}],"version-history":[{"count":10,"href":"https:\/\/nofloods.com\/de\/wp-json\/wp\/v2\/pages\/13989\/revisions"}],"predecessor-version":[{"id":26220,"href":"https:\/\/nofloods.com\/de\/wp-json\/wp\/v2\/pages\/13989\/revisions\/26220"}],"wp:attachment":[{"href":"https:\/\/nofloods.com\/de\/wp-json\/wp\/v2\/media?parent=13989"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}